{"id":16803,"date":"2026-07-13T19:17:06","date_gmt":"2026-07-13T19:17:06","guid":{"rendered":"https:\/\/xmek.in\/?p=16803"},"modified":"2026-07-13T19:17:07","modified_gmt":"2026-07-13T19:17:07","slug":"poker-live-popolazione-azzurra-al-battle-of-melma","status":"publish","type":"post","link":"https:\/\/xmek.in\/index.php\/2026\/07\/13\/poker-live-popolazione-azzurra-al-battle-of-melma\/","title":{"rendered":"Poker Live: popolazione azzurra al Battle of Melma"},"content":{"rendered":"<p>Poker Live: 58 statale per inseguimento al Battle of Mota. Bellingheri al quadro chiusa del Ricevimento. Di Giacomo e Presti ci credono al Main WSOPC<\/p>\n<p>C&#8217;e realmente molto di cui inveire ulteriormente indivis intensa domenica di poker live frammezzo a Fango di nuovo Rozvadov permesso che razza di siamo al day3 del Battle of Melma dei primato (6.039 entries) e abbiamo ben 58 italiani in tallonamento qualora al al di sotto Mota Poker Esibizione siamo al final table, di nuovo con ricerca c&#8217;e di nuovo Giuseppe Bellinghieri. Alle WSOPC Rozvadov continuano Claudio Di Giacomo (per prospetto veste) di nuovo Guido Presti al Main Event laddove Mario Scalia sfiora l&#8217;anello al 6-max. Poker Live.<\/p>\n<p>Il \ufffd600 Battle Of Fanghiglia accosta al day3 con la attrattiva di 58 italiani ed in caccia in mezzo a i 196 players left, una interesse adatto elevata a volte colori nazionale che razza di non riescono bens\u00ec contro attribuirsi la chipleading visto che modello di davanti an qualsiasi troviamo il cipriota Angelos Michael, in certain buon confine visti volte 4.76 milioni sopra gettoni. Accordo i numeri ci parlano di certain edizione da superiorita del BoM con 6.039 entries addirittura un montepremi da 2. euro che sara suddiviso tra rso 196 giocatori per soddisfazione, verso excretion ITM minuscolo da \ufffd2.200 anche una ricca davanti soldo da \ufffd.<\/p>\n<p>In gli azzurri il ottimo addirittura Nico Diperna ad esempio con 3.3 milioni si accomoda al 3\ufffd posto, e per apice-10 c&#8217;e di nuovo Ruggero Magri al 9\ufffd estensione sopra 2.53M. Bene ed Danial Kargarzadeh che tipo di con 2.2M riprendera dal 16\ufffd buco anche concentrazione nonostante riguardo a Luigi Andrea Shehadeh come ha per strumenti 2 milioni. Pi\u00f9 corti troviamo: Gabriele Maesta (65\ufffd sopra 1.19M) e specialmente Luigi Pignataro (173\ufffd verso 370K).<\/p>\n<h2>CHIPCOUNT Celeste BATTLE OF Malta<\/h2>\n<p>3 Nico Diperna 3,370,000 9 Ruggero Magri&#8217; 2,530,000 16 Danial Kargarzadeh 2,205,000 21 Luigi Andrea Shehadeh 2,000,900 29 Giovanni Grande 1,900,000 32 Carmelo Infelise 1,815,000 33 Giovanni Capuano 1,810,000 37 Gianluca Cabitza 1,665,000 45 Onorato Cappiello 1,595,000 51 Vincenzo Mandriota 1,475,000 55 Lorenzo Paolelli 1,395,000 56 Amedeo Popolarit\u00e0 1,390,000 57 Battista Locati 1,375,000 60 Massimiliano Serrani 1,270,000 63 Dalibor Dula 1,215,000 65 Gabriele Signore 1,195,000 68 Giovanni Caggia 1,165,000 78 Alberto Cucca 1,075,000 81 Demetrio Polimeno 1,050,000 85 Francesco Volpe 1,035,000 87 Pieruel Todisco 965,000 95 Redentore Pardo 950,000 102 Mikel Contrazione` 910,000 104 Andrea Zerillo 900,000 105 Giuseppe Ciancio 890,000 108 Milos Stojkovic 870,000 110 Soddisfacentemente Bellezza 860,000 112 Filippo Bechini 830,000 114 Loris Fabbri 800,000 115 Martin Cuccuru 780,000 116 Corrado Martinelli 760,000 118 Marco Giallongo 755,000 123 Santino Arigo&#8217; 730,000 127 Ignazio D&#8217;angelo 700,000 130 Salvatore Salvino 675,000 131 Luca Guiducci 665,000 135 Domenico Insolito 640,000 146 Nicolaj D&#8217;antoni 570,000 152 Gianluca Donini 545,000 155 Lorenzo Ascani 540,000 156 Cosimo De Gennaro 535,000 160 Salvatore Anastasio 500,000 166 Antonio Cammino 450,000 168 Francesco Circolare 445,000 1ico 430,000 171 Roberto Di Giuseppe 410,000 172 Danilo Scevola 410,000 173 Luigi Pignataro 370,000 175 Sequela Saddemi 365,000 176 Luca Tonarelli 365,000 177 Leonardo Romeo 360,000 178 Emanuele Mari 355,000 179 Giuliana Celestini 350,000 182 Vincenzo Lembo 315,000 186 Sergio Previti 265,000 189 Andrea Barreca 230,000 191 Daniele Camerini 180,000<\/p>\n<h2>Giuseppe Bellinghieri al indice finale del Fanghiglia Poker Mostra<\/h2>\n<p>Rimaniamo in ambito perche al \ufffd550 Grand Event del Fango Poker Serata siamo arrivati al <a href=\"https:\/\/fivebet-casino.org\/codice-promozionale\/\">https:\/\/fivebet-casino.org\/codice-promozionale\/<\/a> impalcatura chiusa che razza di qua abbiamo indivis italianio a confidare nella esibizione da \ufffd destinati al comprendere variet\u00e0. Adatto sicuro di 17 mila euro in bisaccia, sara Giuseppe Bellingheri ad attaccare corrente indice chiusa dal 5\ufffd ambito del chipcount con 9.5 milioni mediante chipsanda il francese Benjamin Nicault circa 21.7M.<\/p>\n<p>Nella serata di ieri, che tipo di riprendeva in 30 players left, perdiamo verso apprezzamento 4 azzurri: Samuele Lo Presti (28\ufffd \ufffd \ufffd2.920) riguardo a Gianpiero Barrile (27\ufffd \ufffd \ufffd3.360), Manuel Persico (24\ufffd \ufffd \ufffd3.370), Lorenzo Pannunzi (18\ufffd \ufffd \ufffd4.860).<\/p>\n<h2>CHIPCOUNT FINAL TABLE Fanghiglia POKER Evento<\/h2>\n<p>1 Benjamin Nicault France 21,700,000 2 Ulf Grahs Sweden 18,500,000 3 Joris Ruijs Netherlands 15,900,000 4 Vincent Schueler Germany 12,200,000 5 Giuseppe Bellinghieri Italy 9,500,000 6 Vester Vergeest Netherlands 8,100,000 7 Jeffrey Gregor Denmark 7,800,000 8 Toni Ravnak Serbia 5,700,000<\/p>\n<h2>Di Giacomo e Presti al Main Event WSOPC Rozvadov. Scalia sfiora l&#8217;anello<\/h2>\n<p>Ci spostiamo verso Repubblica Ceca anche, a le WSOPC Rozvadov in l&#8217;atteso \ufffd1.500 Main Event che tipo di entra nelle circa fasi calde vidimazione che razza di al estremit\u00e0 della anniversario di un giorno fa sono rimasti 24 players left verso trattare l&#8217;anello delle World Series of Poker Circuit, mediante excretion contrasto come ha richiamato 544 iscritti.<\/p>\n<p>Si riprendera verso per mente il barbarico, di origini italiane, Stefano Aprile, con 2.35M, pero alquanto in fondo c&#8217;e il nostro Claudio Di Giacomo ad esempio lo tallona mediante 2. di nuovo che tipo di si controllo costante. Dovra invece redimere dal 17\ufffd spazio (755K) l&#8217;altro italiano a bazzecola, Guido Presti.<\/p>\n<h2>CHIPCOUNT MAIN EVENT WSOPC ROZVADOV<\/h2>\n<p>Accordo Mario Scalia ha lambito la conquista del ring nell&#8217;evento \ufffd600 NLH 6-Max ciononostante nel mente an intelligenza finale sinon riguardo a sopra il tedesco Felix Peter Seelentang come varco domiciliare diritto ed inizialmente moneta, mentre Scalia si consola con certain ricompensa da euro.<\/p>\n<p>Sono taluno dei fondatori di PIW, Poker Italia Web ed seguo il mondo del poker live anche online da al di la 10 anni. Nuovo al poker sono insecable sensibile attirato di passatempo ancora di stabile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poker Live: 58 statale per inseguimento al Battle of Mota. Bellingheri al quadro chiusa del Ricevimento. Di Giacomo e Presti ci credono al Main WSOPC C&#8217;e realmente molto di cui inveire ulteriormente indivis intensa domenica di poker live frammezzo a Fango di nuovo Rozvadov permesso che razza di siamo al day3 del Battle of Melma &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/xmek.in\/index.php\/2026\/07\/13\/poker-live-popolazione-azzurra-al-battle-of-melma\/\"> <span class=\"screen-reader-text\">Poker Live: popolazione azzurra al Battle of Melma<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/xmek.in\/index.php\/wp-json\/wp\/v2\/posts\/16803"}],"collection":[{"href":"https:\/\/xmek.in\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xmek.in\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xmek.in\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/xmek.in\/index.php\/wp-json\/wp\/v2\/comments?post=16803"}],"version-history":[{"count":1,"href":"https:\/\/xmek.in\/index.php\/wp-json\/wp\/v2\/posts\/16803\/revisions"}],"predecessor-version":[{"id":16804,"href":"https:\/\/xmek.in\/index.php\/wp-json\/wp\/v2\/posts\/16803\/revisions\/16804"}],"wp:attachment":[{"href":"https:\/\/xmek.in\/index.php\/wp-json\/wp\/v2\/media?parent=16803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xmek.in\/index.php\/wp-json\/wp\/v2\/categories?post=16803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xmek.in\/index.php\/wp-json\/wp\/v2\/tags?post=16803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}